{"id":3802,"date":"2022-03-06T10:55:14","date_gmt":"2022-03-06T09:55:14","guid":{"rendered":"http:\/\/www.contrabanda.org\/?p=3802"},"modified":"2022-05-16T16:43:10","modified_gmt":"2022-05-16T14:43:10","slug":"especial-8m-i-18-anys-del-aleteo-desequilibrado","status":"publish","type":"post","link":"https:\/\/www.contrabanda.org\/ca\/2022\/03\/06\/especial-8m-i-18-anys-del-aleteo-desequilibrado\/","title":{"rendered":"Especial 8M i 18 anys d&#8217;El Aleteo desequilibrado"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: left\"><a href=\"http:\/\/www.contrabanda.org\/wp-content\/uploads\/2022\/03\/IMG-20220306-WA0005.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3823 size-medium\" src=\"http:\/\/www.contrabanda.org\/wp-content\/uploads\/2022\/03\/IMG-20220306-WA0005-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.contrabanda.org\/wp-content\/uploads\/2022\/03\/IMG-20220306-WA0005-300x300.jpg 300w, https:\/\/www.contrabanda.org\/wp-content\/uploads\/2022\/03\/IMG-20220306-WA0005-1024x1024.jpg 1024w, https:\/\/www.contrabanda.org\/wp-content\/uploads\/2022\/03\/IMG-20220306-WA0005-150x150.jpg 150w, https:\/\/www.contrabanda.org\/wp-content\/uploads\/2022\/03\/IMG-20220306-WA0005-768x768.jpg 768w, https:\/\/www.contrabanda.org\/wp-content\/uploads\/2022\/03\/IMG-20220306-WA0005.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Aquest dimarts dia 8 de mar\u00e7, a partir de les 11h i com \u00e9s habitual, les dones de Contrabanda FM fem emissi\u00f3 especial durant el 8M i alhora celebrem els 18 anys del programa &#8220;El aleteo desequilibrado&#8221;.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Aquest dimarts dia 8 de mar\u00e7, a partir de les 11h i com \u00e9s habitual, les dones de Contrabanda FM fem emissi\u00f3 especial durant el 8M i alhora celebrem els 18 anys del programa &#8220;El aleteo desequilibrado&#8221;.<\/p>\n","protected":false},"author":14,"featured_media":3823,"comment_status":"registered_only","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[179],"tags":[],"class_list":["post-3802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"acf":[],"jetpack_featured_media_url":"https:\/\/www.contrabanda.org\/wp-content\/uploads\/2022\/03\/IMG-20220306-WA0005.jpg","_links":{"self":[{"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/posts\/3802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/comments?post=3802"}],"version-history":[{"count":27,"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/posts\/3802\/revisions"}],"predecessor-version":[{"id":3850,"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/posts\/3802\/revisions\/3850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/media\/3823"}],"wp:attachment":[{"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/media?parent=3802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/categories?post=3802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.contrabanda.org\/ca\/wp-json\/wp\/v2\/tags?post=3802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}